{"id":4328,"date":"2026-03-04T18:45:16","date_gmt":"2026-03-04T18:45:16","guid":{"rendered":"https:\/\/reinike.loupwebs.cl\/?post_type=instalacion_y_equipo&#038;p=4328"},"modified":"2026-03-04T18:45:31","modified_gmt":"2026-03-04T18:45:31","slug":"instalaciones-y-maquinaria-3","status":"publish","type":"instalacion_y_equipo","link":"https:\/\/reinike.loupwebs.cl\/en\/instalacion_y_equipo\/instalaciones-y-maquinaria-3\/","title":{"rendered":"INSTALACIONES Y MAQUINARIA#5"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Contamos con m\u00e1s de 42.500 m\u00b2 de superficie productiva, distribuidos en plantas de fabricaci\u00f3n, montaje, pintura, despacho, \u00e1reas de pruebas y control de calidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>","protected":false},"excerpt":{"rendered":"<p>Contamos con m\u00e1s de 42.500 m\u00b2 de superficie productiva, distribuidos en plantas de fabricaci\u00f3n, montaje, pintura, despacho, \u00e1reas de pruebas y control de calidad.<\/p>","protected":false},"featured_media":395,"template":"","meta":{"_acf_changed":false},"categories":[],"tags":[],"class_list":["post-4328","instalacion_y_equipo","type-instalacion_y_equipo","status-publish","has-post-thumbnail","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/reinike.loupwebs.cl\/en\/wp-json\/wp\/v2\/instalacion_y_equipo\/4328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/reinike.loupwebs.cl\/en\/wp-json\/wp\/v2\/instalacion_y_equipo"}],"about":[{"href":"https:\/\/reinike.loupwebs.cl\/en\/wp-json\/wp\/v2\/types\/instalacion_y_equipo"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/reinike.loupwebs.cl\/en\/wp-json\/wp\/v2\/media\/395"}],"wp:attachment":[{"href":"https:\/\/reinike.loupwebs.cl\/en\/wp-json\/wp\/v2\/media?parent=4328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/reinike.loupwebs.cl\/en\/wp-json\/wp\/v2\/categories?post=4328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/reinike.loupwebs.cl\/en\/wp-json\/wp\/v2\/tags?post=4328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}